{"id":238821,"date":"2025-09-25T13:10:57","date_gmt":"2025-09-25T11:10:57","guid":{"rendered":"https:\/\/nemborn.com\/datenschutz-und-politik\/"},"modified":"2025-09-25T13:20:12","modified_gmt":"2025-09-25T11:20:12","slug":"privacy-policy-4","status":"publish","type":"page","link":"https:\/\/nemborn.com\/de\/privacy-policy-4\/","title":{"rendered":"Datenschutz und Politik"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"238821\" class=\"elementor elementor-238821 elementor-228322\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a99746f e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"a99746f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-d61d8c5 e-con-full centre e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"d61d8c5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40f1ab7 elementor-widget elementor-widget-heading\" data-id=\"40f1ab7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Datenschutzbestimmungen<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-78d4a37 centre e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"78d4a37\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f86e81c elementor-widget elementor-widget-text-editor\" data-id=\"f86e81c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Wer wir sind<\/strong><\/p><p>Mit Wirkung vom 26. Januar 2021 haben Assemble A\/S (&#8222;Assemble&#8220;) und seine Tochtergesellschaften (zusammen die &#8222;Assemble-Gruppe&#8220; oder &#8222;wir&#8220; oder &#8222;uns&#8220; oder &#8222;unser&#8220;) unsere Datenschutzrichtlinie aktualisiert.<\/p><p><strong>Zweck dieser Datenschutzrichtlinie<\/strong><\/p><p>Der Schutz Ihrer Daten ist wichtig. Wir verpflichten uns zur Sicherheit, zum Schutz und zur Vertraulichkeit von Informationen, die Sie uns oder in Ihrem Namen zur Verf\u00fcgung stellen oder bei denen es sich um Daten handelt, mit denen wir Sie durch die Bereitstellung von Datenverarbeitungs- und\/oder Datenspeicherdiensten unterst\u00fctzen. Diese Datenschutzrichtlinie beschreibt unsere aktuellen Richtlinien und Praktiken in Bezug auf alle pers\u00f6nlichen Daten, die wir von Ihnen direkt, \u00fcber die Website oder, falls Sie ein Elternteil, ein Vormund oder ein Betreuer sind, von einer Kindertagesst\u00e4tte oder Schule, mit der wir zusammenarbeiten, erhalten.  <\/p><p>Pers\u00f6nliche Daten sind alle Informationen, die Sie identifizieren, wie z. B. Ihr Name, Ihre E-Mail-Adresse, Ihre Telefonnummer und Ihre Position.<\/p><p><strong>Wie wir den Datenschutz einhalten  <\/strong><\/p><p>In Anbetracht unserer Verantwortung, die Allgemeine Datenschutzverordnung und andere geltende Gesetze einzuhalten, haben wir entsprechendes Personal ernannt, das die Einhaltung aller Datenschutz- und E-Privacy-Vorschriften in unserem Unternehmen \u00fcberwacht und sicherstellt. Sie k\u00f6nnen sich an <a href=\"mailto:privacy@assemble.world\">privacy@assemble.world<\/a> wenden, wenn Sie Fragen haben oder weitere Informationen ben\u00f6tigen. <\/p><p><strong>Benachrichtigung \u00fcber \u00c4nderungen an unserer Datenschutzrichtlinie<\/strong><\/p><p>Wir verbessern st\u00e4ndig unsere Kommunikationsmethoden und f\u00fcgen dieser Website und unseren bestehenden Diensten neue Funktionen und Merkmale hinzu. Aufgrund dieser laufenden Ver\u00e4nderungen, Gesetzes\u00e4nderungen und der sich wandelnden Technologie werden sich unsere Datenschutzpraktiken von Zeit zu Zeit \u00e4ndern. Falls und wenn sich unsere Datenschutzpraktiken \u00e4ndern, werden wir diese Datenschutzerkl\u00e4rung aktualisieren, um unsere neuen Praktiken zu beschreiben. Wir empfehlen Ihnen, diese Seite regelm\u00e4\u00dfig zu besuchen.   <\/p><p>Diese Richtlinie wurde zuletzt am 26. Januar 2021 aktualisiert.<\/p><p>Wir haben diese Richtlinie aktualisiert, um der Verantwortung Rechnung zu tragen, die wir im Rahmen der Allgemeinen Datenschutzverordnung haben werden.<\/p><p><strong>Die Informationen, die wir sammeln<\/strong><\/p><p>Wir speichern nur personenbezogene Daten, die f\u00fcr unsere Beziehungen zu einer bestimmten betroffenen Person unmittelbar relevant sind und deren Verarbeitung durch uns rechtm\u00e4\u00dfig erfolgen kann &#8211; zum Beispiel in Verfolgung unserer berechtigten Interessen, wie in dieser Richtlinie erl\u00e4utert, oder f\u00fcr Zwecke im Zusammenhang mit dem Abschluss eines Vertrags mit einer Organisation und der anschlie\u00dfenden Erf\u00fcllung dieses Vertrags. Diese Daten werden in der Art und Weise gespeichert und verarbeitet, wie wir sie in dieser Richtlinie beschreiben. <\/p><p>M\u00f6glicherweise wurden Sie \u00fcber einen Link, den wir Ihnen zur Verf\u00fcgung gestellt haben, zu dieser Richtlinie weitergeleitet. Wir machen Einzelpersonen auf unsere Politik in Bezug auf den Besitz und die Verarbeitung der Daten dieser Person zum Zeitpunkt der Erhebung der betreffenden personenbezogenen Daten aufmerksam. <\/p><p><strong>Wie wir pers\u00f6nliche Informationen sammeln<\/strong><\/p><p>Wir k\u00f6nnen Ihre pers\u00f6nlichen Daten in dem Moment erfassen, in dem Sie eine Anfrage an Assemble A\/S stellen. Dazu geh\u00f6ren Ihre telefonischen Anfragen sowie Anfragen, die wir auf Messen und bei anderen Marketingaktivit\u00e4ten erhalten, die wir durchf\u00fchren. Wir nehmen Ihre Daten nur dann auf einer Grundlage auf, die uns berechtigt, diese pers\u00f6nlichen Daten zu speichern und zu verwenden, wenn Sie ausdr\u00fccklich zugestimmt haben, dass wir die Daten speichern d\u00fcrfen und f\u00fcr jeden Zweck, f\u00fcr den wir diese Daten verwenden wollen.  <\/p><p>Wir sammeln und speichern personenbezogene Daten \u00fcber Nutzer unserer Produkte und Dienstleistungen, wenn eine Anfrage oder Bitte um Unterst\u00fctzung an uns gerichtet wurde.<\/p><p>Wenn Sie sich f\u00fcr eine Schulungsveranstaltung oder Konferenz anmelden, ben\u00f6tigen wir ebenfalls pers\u00f6nliche Daten, damit wir mit Ihnen \u00fcber die Veranstaltung kommunizieren k\u00f6nnen.<\/p><p>Wenn Sie sich als Teilnehmer in einem von uns angebotenen Forum registrieren, werden wir Ihre Daten zum Zweck der Verwaltung des Forums speichern. Alle weiteren Daten, die Sie uns zur Verf\u00fcgung stellen, wie z.B. Lehrmaterial, Meinungen und Kommentare, werden aufbewahrt und stehen anderen registrierten Nutzern in \u00dcbereinstimmung mit den f\u00fcr das jeweilige Forum geltenden und dort angezeigten Regeln zur Verf\u00fcgung. <\/p><p>Wir sammeln und verwenden Informationen von Nutzern, die unsere Dienste entweder \u00fcber mobile Anwendungen auf iOS (Apple App Store) oder Android (Google Play Store) oder \u00fcber unsere Webanwendungen nutzen.<\/p><h3>Unser Umgang mit Ihren pers\u00f6nlichen Informationen<\/h3><p><strong>F\u00fcr unsere Marketingzwecke<\/strong><\/p><p>Wenn Sie jetzt oder zu einem sp\u00e4teren Zeitpunkt angeben, dass Sie damit einverstanden sind, werden wir die pers\u00f6nlichen Daten, die Sie uns zur Verf\u00fcgung stellen, aufbewahren, damit wir sie verwenden k\u00f6nnen:<\/p><ul><li>Sie zu kontaktieren, um Sie \u00fcber neue Dienstleistungen und Produkte zu informieren, die wir anbieten werden;<\/li><li>Ihnen angeforderte Informationen \u00fcber unsere Dienstleistungen oder Produkte zu senden; oder<\/li><li>Sie \u00fcber Aktualisierungen bei der Weiterentwicklung von Produkten und\/oder Dienstleistungen, f\u00fcr die Sie Interesse bekundet haben, zu informieren.<\/li><\/ul><p>Wir sind der Ansicht, dass wir Ihre pers\u00f6nlichen Daten im Rahmen der Verfolgung unserer legitimen Interessen als Unternehmen, das sich f\u00fcr den Erfolg des Bildungssektors einsetzt, verwenden d\u00fcrfen.<\/p><p>Unsere E-Mails, die auf der oben genannten Grundlage bereitgestellt werden, enthalten immer eine Opt-out-Option f\u00fcr weitere Mitteilungen.<\/p><p><strong>F\u00fcr den Abschluss von Vertr\u00e4gen und die Verwaltung und Administration des Vertrags<\/strong><\/p><p>Wir verwenden die in unserem Besitz befindlichen pers\u00f6nlichen Daten, um Anfragen zu notieren, die in irgendeiner Weise gestellt werden, die im Rahmen des Vertrags vorgesehen ist. Dazu geh\u00f6rt auch die Nutzung der von uns angebotenen Helpline durch Nutzer unserer Produkte oder Dienstleistungen. <\/p><p><strong>Zum Zweck der Erbringung von Dienstleistungen, wie sie in unseren Vertr\u00e4gen mit Kindertagesst\u00e4tten und Schulen und anderen Kunden gefordert werden.<\/strong><\/p><p>Wir speichern Informationen \u00fcber bestimmte Personen f\u00fcr Zwecke im Zusammenhang mit der Verwaltung von Vertr\u00e4gen, die wir mit Kindertagesst\u00e4tten, Schulen und anderen Kunden unseres Unternehmens haben. Wir bewahren diese Informationen so lange auf, wie wir einen Vertrag mit der betreffenden Organisation haben oder bis wir \u00fcber einen Wechsel der Person(en) informiert werden, mit der\/denen wir im Rahmen der Verwaltung und des Managements des Vertrags arbeiten sollen. In diesem Fall werden die Daten der vorherigen Person sofort gel\u00f6scht, es sei denn, wir erhalten von dieser Person die Zustimmung, weiterhin in Bezug auf unsere Produkte und Dienstleistungen zu kommunizieren. <\/p><p>Wir f\u00fchren Aufzeichnungen \u00fcber Personen, die sich an die von uns angebotenen Beratungsdienste wenden (dies gilt auch f\u00fcr F\u00e4lle, in denen eine Person uns auf anderem Wege kontaktiert, aber an den Helpdesk verwiesen wird).<\/p><p>Wir verf\u00fcgen \u00fcber Angaben zu Ihrem Datenschutzbeauftragten oder, falls Sie keinen haben, zu der Person, die Sie als Verantwortlicher f\u00fcr Datenschutzangelegenheiten benannt haben.<\/p><p>Von Zeit zu Zeit haben wir auch Zugang zu pers\u00f6nlichen und anderen Daten, f\u00fcr die eine Kindertagesst\u00e4tte oder Schule, die unser Kunde ist, verantwortlich ist. Diese Daten werden von der Kindertagesst\u00e4tte oder der Schule entweder direkt oder \u00fcber einen Dritten, der \u00fcblicherweise als Datenextraktor bezeichnet wird, bereitgestellt. Bitte lesen Sie die Datenschutzrichtlinien der Kindertagesst\u00e4tte oder Schule, an der Sie interessiert sind, um zu verstehen, wie sie von uns erwarten, dass wir mit ihnen als Datenverarbeiter zusammenarbeiten.  <\/p><p>Informationen, die bei der Nutzung unserer Dienste \u00fcber mobile Anwendungen auf iOS (Apple App Store) oder Android (Google Play Store) oder durch die Nutzung unserer Webanwendungen gesammelt werden, werden f\u00fcr Folgendes verwendet:<\/p><ul><li>Informationen und Inhalte, die Sie uns zur Verf\u00fcgung stellen, werden ausschlie\u00dflich dazu verwendet, unsere Dienstleistungen f\u00fcr eine Kindertagesst\u00e4tte oder Schule bereitzustellen und zu personalisieren.<\/li><li>Standortbezogene Informationen werden f\u00fcr den Check-In und Check-Out in Kindertagesst\u00e4tten und Schulen verwendet. Die standortbezogenen Informationen sind Ihr aktueller GPS-Standort, um festzustellen, ob Sie sich an einem Ort befinden, an dem Sie in einer Kindertagesst\u00e4tte oder Schule ein- oder auschecken k\u00f6nnen. <\/li><li>Ger\u00e4teinformationen wie eindeutige Kennungen, Ger\u00e4te-IDs und Ger\u00e4tesignale werden nur im Falle einer Support-Anfrage an den Assemble-Helpdesk gesammelt und verwendet, um eine geeignete L\u00f6sung zu finden.<\/li><\/ul><p><strong>Zur Verwaltung von Veranstaltungen, die wir <\/strong><b>Organisieren<\/b><\/p><p>Wir verwenden die bei der Anmeldung zur Teilnahme an einer von uns organisierten Veranstaltung, wie z. B. Schulungsworkshops, Seminare und Veranstaltungen auf Messen, bereitgestellten Informationen, um Sie vor der Veranstaltung auf dem Laufenden zu halten. Wir k\u00f6nnen Sie auch im Nachhinein kontaktieren, um Ihnen Informationen \u00fcber den Tag, Angebote und Dienstleistungen zukommen zu lassen und\/oder um Sie zu bitten, uns ein Feedback zu der von Ihnen besuchten Veranstaltung zu geben. <\/p><p><strong>Wie wir<\/strong><strong> Ihre Informationen weitergeben <\/strong> <\/p><p>Wir sichern Ihre Daten in ISO 27001-zertifizierten Rechenzentren in der Europ\u00e4ischen Union.<\/p><p><strong>Wie lange bewahren wir Ihre pers\u00f6nlichen Daten auf?<\/strong><\/p><p>Wenn Sie eine Anfrage an uns richten, die nicht dazu f\u00fchrt, dass wir Ihnen ein Angebot f\u00fcr eines unserer Produkte und\/oder eine unserer Dienstleistungen unterbreiten, werden wir die uns vorliegenden Informationen l\u00f6schen oder, wenn wir die Informationen f\u00fcr die Zwecke der Weiterentwicklung unserer Produkte und Dienstleistungen aufbewahren m\u00f6chten, die Informationen aufbewahren, ohne dass es sich dabei um personenbezogene Daten handelt, und zwar unmittelbar danach.<\/p><p>Wir speichern Informationen \u00fcber Personen, die von Kindertagesst\u00e4tten oder Schulen und anderen Kunden als bevollm\u00e4chtigt benannt wurden, um mit uns im Vertragsmanagement und in der Verwaltung zusammenzuarbeiten, solange diese Bevollm\u00e4chtigung besteht oder bis der Vertrag mit uns endet, falls dieser fr\u00fcher endet. Informationen \u00fcber Kunden, mit denen kein Vertrag mehr besteht, werden f\u00fcr einen angemessenen Zeitraum aufbewahrt, w\u00e4hrend noch Verhandlungen \u00fcber eine Verl\u00e4ngerung der Beziehung gef\u00fchrt werden. Gelingt es nicht, eine Verl\u00e4ngerung zu erreichen, werden die Daten anonymisiert oder vollst\u00e4ndig gel\u00f6scht.  <\/p><p>Wir verarbeiten im Auftrag einer Kindertagesst\u00e4tte oder einer Schule Daten (einschlie\u00dflich personenbezogener Daten), wenn wir Datenservicezentren zur Verf\u00fcgung stellen, so lange wir in unserem Vertrag mit dieser Partei dazu verpflichtet sind, und f\u00fcr einen angemessenen Zeitraum danach zum Zwecke von Verl\u00e4ngerungsgespr\u00e4chen.<\/p><p>Wenn Sie sich f\u00fcr eine Veranstaltung, die wir organisieren oder an der wir teilnehmen, anmelden oder daran teilnehmen und wir Ihre pers\u00f6nlichen Daten in diesem Zusammenhang erhalten, behalten wir uns das Recht vor, Ihnen danach Informationen zu senden, um Produkte und Dienstleistungen an Sie zu vermarkten; in diesem Fall werden Ihre pers\u00f6nlichen Daten weiterhin wie oben in dieser Richtlinie erl\u00e4utert gespeichert. In allen anderen F\u00e4llen werden Ihre Daten sp\u00e4testens 24 Monate nach der Veranstaltung gel\u00f6scht. <\/p><p>Wenn Sie sich in einem Forum auf unserer Website, in der Assemble A\/S-Community oder innerhalb unserer Produkte beteiligen, werden Ihre pers\u00f6nlichen Daten mit anderen Nutzern geteilt und so lange gespeichert, wie Sie ein registrierter Nutzer bleiben. Wenn Sie sich abmelden m\u00f6chten, m\u00fcssen Sie das Datenb\u00fcro unter der am Anfang dieses Dokuments angegebenen Adresse kontaktieren. <\/p><p><strong>Abbestellung und Recht auf L\u00f6schung pers\u00f6nlicher Daten<\/strong><\/p><p>Wenn Sie zugestimmt haben, dass wir Sie zu einem der oben genannten Zwecke kontaktieren, Sie aber keine E-Mails mehr von uns erhalten m\u00f6chten oder Ihre Auswahl bez\u00fcglich der Art und Weise, wie oder womit wir Sie kontaktieren, \u00e4ndern m\u00f6chten, folgen Sie bitte der in der E-Mail enthaltenen Option &#8222;Abmelden&#8220; oder senden Sie uns eine E-Mail an die in Abschnitt 1 angegebene Adresse mit dem Betreff &#8222;E-Mail abbestellen&#8220;. Wir werden so schnell wie m\u00f6glich darauf reagieren. <\/p><p>Sie k\u00f6nnen uns auch an die am Anfang dieser Richtlinie angegebene Adresse schreiben.<\/p><p>Wenn Sie sich von unseren Mailinglisten abmelden, nehmen wir nur dann wieder Kontakt mit Ihnen auf, wenn Sie zugestimmt haben, dass wir Ihre Daten erneut erhalten und dieser Kontakt von Ihnen genehmigt wurde.<\/p><p><strong>\u00dcber diese Website gesammelte anonyme Daten<\/strong><\/p><p>Zus\u00e4tzlich zu den Informationen, die wir wie oben beschrieben sammeln, verwenden wir Technologien, um anonyme Informationen \u00fcber die Nutzung unserer Website zu sammeln. Zum Beispiel protokolliert unser Webserver automatisch, welche Seiten unserer Website unsere Besucher aufrufen, ihre IP-Adressen und die von ihnen verwendeten Webbrowser. Mit dieser Technologie k\u00f6nnen Sie nicht pers\u00f6nlich identifiziert werden. Sie erm\u00f6glicht uns lediglich die Erstellung von Statistiken \u00fcber unsere Besucher und deren Nutzung unserer Website.  <\/p><p>Unsere Website enth\u00e4lt Hyperlinks zu anderen Seiten auf unserer Website. Wir k\u00f6nnen Technologien einsetzen, um zu verfolgen, wie oft diese Links genutzt werden und welche Seiten auf unserer Website unsere Besucher besuchen wollen. Auch diese Technologie identifiziert Sie nicht pers\u00f6nlich &#8211; sie erm\u00f6glicht uns lediglich die Erstellung von Statistiken \u00fcber die Nutzung dieser Hyperlinks.  <\/p><p>Wenn Sie nach dem Besuch unserer Website eine offizielle Anfrage an uns richten, um weitere Informationen anzufordern und uns Ihren Namen und Ihre Kontaktdaten mitzuteilen, ist es m\u00f6glich, dass Ihre IP-Adresse mit dem anonymen Surfen auf den Seiten verkn\u00fcpft wird, um uns zu helfen, zu verstehen, woran Sie interessiert sind. Auf Wunsch k\u00f6nnen diese Daten gel\u00f6scht werden. Wenden Sie sich dazu bitte an unser Datenb\u00fcro, wie in Abschnitt 1 dieses Dokuments beschrieben. <\/p><p><strong>Cookies und \u00e4hnliche Technologien<\/strong><\/p><p>Um die im vorhergehenden Absatz beschriebenen anonymen Daten zu sammeln, k\u00f6nnen wir auf unserer Website die Cookie-Technologie verwenden.<\/p><p>Ein Cookie ist eine kleine Information, die an Ihren Browser gesendet und auf der Festplatte Ihres Computers, Mobiltelefons oder anderen Ger\u00e4ts gespeichert wird. Cookies besch\u00e4digen Ihren Computer nicht. <\/p><p>Sie k\u00f6nnen Ihren Browser so einstellen, dass er Sie benachrichtigt, wenn Sie ein Cookie erhalten. So k\u00f6nnen Sie selbst entscheiden, ob Sie das Cookie akzeptieren m\u00f6chten oder nicht. Einige der Dienste und Funktionen, die auf unserer Website angeboten werden, funktionieren jedoch m\u00f6glicherweise nicht richtig, wenn Ihre Cookies deaktiviert sind.  <\/p><h3>Wir verwenden zwei Arten von Cookies auf unserer Website:<\/h3><p><strong>Streng Notwendige Cookies<\/strong><\/p><p>Diese Cookies sind unerl\u00e4sslich, damit Sie sich auf der Website bewegen und ihre Funktionen nutzen k\u00f6nnen. Ohne diese Cookies k\u00f6nnen die von Ihnen angeforderten Dienste nicht bereitgestellt werden. Sie werden gel\u00f6scht, wenn Sie den Browser schlie\u00dfen.  <\/p><p><strong>Leistungs-Cookies (z.B. Google Analytics)<\/strong><\/p><p>Diese Cookies sammeln in anonymer Form Informationen dar\u00fcber, wie Besucher unsere Website nutzen. Sie erm\u00f6glichen es uns, die Anzahl der Besucher zu erkennen und zu z\u00e4hlen und zu sehen, wie sich die Besucher auf der Website bewegen, wenn sie sie nutzen. Dies hilft uns, die Website kontinuierlich zu verbessern.  <\/p><p>Wir k\u00f6nnen Ihre IP-Adresse auch verwenden, um Probleme mit unserem Server zu diagnostizieren, unsere Website zu verwalten und den Service, den wir Ihnen anbieten, zu verbessern. Eine IP-Adresse ist ein numerischer Code, der Ihren Computer in einem Netzwerk, oder in diesem Fall im Internet, identifiziert. Ihre IP-Adresse kann auch verwendet werden, um allgemeine demografische Informationen zu sammeln.  <\/p><p>Wir k\u00f6nnen IP-Lookups durchf\u00fchren, um festzustellen, von welcher Domain Sie kommen (z.B. aol.com, yourcompany.com), um die Demographie unserer Nutzer genauer zu erfassen.<\/p><p>Informationen aus diesen Arten von Cookies und Technologien oder \u00fcber die Nutzung der Website werden nicht mit Informationen \u00fcber Sie aus anderen Quellen kombiniert. Keines der Cookies oder Technologien, die wir verwenden, identifiziert Sie pers\u00f6nlich. <\/p><p><strong>Einverst\u00e4ndnis<\/strong><\/p><p>Um den geltenden Gesetzen zu entsprechen, m\u00fcssen wir Sie um Ihr Einverst\u00e4ndnis bitten, die oben beschriebenen Performance-Cookies zu setzen. Wenn Sie auf unsere Website gelangen, erscheint ein Banner, in dem Sie um Ihre Zustimmung zur Platzierung von Performance-Cookies auf Ihrem Ger\u00e4t gebeten werden. Wenn Sie unsere Website weiter nutzen oder auf &#8218;OK&#8216; klicken, gehen wir davon aus, dass Sie mit der Speicherung von Cookies auf Ihrem Ger\u00e4t einverstanden sind. Wenn Sie damit nicht einverstanden sind, verlassen Sie bitte sofort unsere Website. Sobald Sie Ihr Einverst\u00e4ndnis gegeben haben, wird diese Meldung bei einem erneuten Besuch nicht mehr erscheinen. Wenn Sie oder ein anderer Benutzer Ihres Computers Ihre Zustimmung jederzeit widerrufen m\u00f6chten, k\u00f6nnen Sie dies tun, indem Sie die Einstellungen Ihres Browsers \u00e4ndern.     <\/p><p><strong>Wenn Sie Zugang zu den von uns gespeicherten pers\u00f6nlichen Daten w\u00fcnschen<\/strong><\/p><p>Sie sind berechtigt, eine Anfrage zu stellen, damit wir Ihnen alle personenbezogenen Daten, die wir \u00fcber Sie gespeichert haben, zur Verf\u00fcgung stellen, indem Sie einen Antrag auf Zugang zu diesen Daten stellen. Wenn wir Informationen \u00fcber Sie haben, werden wir: <\/p><ul><li>Ihnen eine Beschreibung zu geben;<\/li><li>sagen Ihnen, warum wir es halten;<\/li><li>Ihnen mitteilen, an wen die Daten weitergegeben werden k\u00f6nnten; und<\/li><li>Ihnen eine Kopie der Informationen in einer verst\u00e4ndlichen Form zukommen lassen<\/li><\/ul><p>alle Umst\u00e4nde, au\u00dfer wenn Sie mehrere Kopien der angeforderten Informationen anfordern.<\/p><p>Wir werden auch alle pers\u00f6nlichen Daten korrigieren, erg\u00e4nzen oder l\u00f6schen, von denen Sie uns sagen, dass sie unrichtig sind, und alle dritten Empf\u00e4nger \u00fcber die notwendigen \u00c4nderungen informieren. Sie k\u00f6nnen alle Informationen, die Sie uns gegeben haben, aktualisieren, indem Sie uns unter unserer registrierten Adresse oder der oben angegebenen E-Mail-Adresse kontaktieren. <\/p><p>Wir erwarten von den Schulen, dass sie im Rahmen ihrer Vereinbarung mit uns sicherstellen, dass die von ihnen bereitgestellten personenbezogenen Daten bei Bedarf aktualisiert werden, um ihre Richtigkeit zu gew\u00e4hrleisten.<\/p><p><strong>Offenlegung Ihrer pers\u00f6nlichen Informationen<\/strong><\/p><p>Wir geben Ihre pers\u00f6nlichen Daten nicht an Dritte weiter, verkaufen sie nicht und geben sie auch nicht an Dritte weiter, es sei denn, diese Datenschutzrichtlinie sieht etwas anderes vor und Sie haben der Weitergabe und dem Zweck der Weitergabe ausdr\u00fccklich zugestimmt.<\/p><p>Wir k\u00f6nnen minimale Informationen mit genehmigten Anwendungen von Drittanbietern teilen, \u00fcbertragen oder offenlegen, die Ihre Kindertagesst\u00e4tte oder Schule abonniert hat und die ein Single Sign On (SSO) von Assemble-Produkten erm\u00f6glichen m\u00f6chten. Sie werden immer um Ihr Einverst\u00e4ndnis gebeten &#8211; entweder indem Sie uns bitten, das SSO f\u00fcr Sie einzurichten, oder indem Sie Links und Anweisungen zu Websites von Drittanbietern folgen und die entsprechende Einwilligung ausf\u00fcllen. <\/p><p>Wir k\u00f6nnen die Informationen in unseren Datenbanken und Serverprotokollen auch weitergeben, \u00fcbertragen oder offenlegen, um gesetzliche Anforderungen zu erf\u00fcllen, oder im Falle eines B\u00f6rsengangs, eines Verkaufs, einer Fusion, einer Umstrukturierung, einer Aufl\u00f6sung, einer Ver\u00e4u\u00dferung aller oder eines Teils unserer Verm\u00f6genswerte oder eines \u00e4hnlichen Ereignisses. Wir werden Sie \u00fcber eine solche \u00dcbertragung oder Offenlegung informieren, wenn dies gesetzlich vorgeschrieben ist. <\/p><p><strong>Datenzugriff und Korrekturen<\/strong><\/p><p>Antr\u00e4ge auf L\u00f6schung personenbezogener Daten unterliegen allen anwendbaren rechtlichen und ethischen Melde- oder Dokumentenaufbewahrungspflichten, die uns auferlegt werden.<\/p><p><strong>Links zu anderen Websites<\/strong><\/p><p>Unsere Website kann Hyperlinks zu Websites enthalten, die nicht von uns betrieben werden. Wir empfehlen Ihnen dringend, die Datenschutzrichtlinien auf den von Ihnen besuchten Websites zu lesen, bevor Sie die Website nutzen oder pers\u00f6nliche Daten \u00fcber sich selbst angeben. <\/p><p><strong>\u00dcbertragung von Daten ins Ausland<\/strong><\/p><p>Wenn Sie diese Website von einem anderen Land aus besuchen als dem, in dem sich unsere Server befinden (derzeit D\u00e4nemark und Deutschland), f\u00fchren die verschiedenen Kommunikationen zwangsl\u00e4ufig zur \u00dcbertragung von Informationen \u00fcber internationale Grenzen hinweg. Indem Sie diese Website besuchen und elektronisch mit uns kommunizieren, stimmen Sie der Verarbeitung und \u00dcbermittlung Ihrer pers\u00f6nlichen Daten gem\u00e4\u00df dieser Datenschutzrichtlinie zu. <\/p><p><strong>Kontaktieren Sie uns<\/strong><\/p><p>Wenn Sie Fragen zu dieser Richtlinie oder zu den Datenschutzpraktiken der Assemble Group haben, kontaktieren Sie uns bitte per E-Mail unter <a href=\"mailto:privacy@assemble.world\">privacy@assemble.world<\/a> oder unter<\/p><p>Assemble A\/S<br>Valuersvej 12<br>2900 Hellerup<br>D\u00e4nemark<\/p><p><strong>Englische Version Steuerelemente<\/strong><\/p><p>Nicht-englische \u00dcbersetzungen dieser Richtlinie werden nur aus praktischen Gr\u00fcnden zur Verf\u00fcgung gestellt. Im Falle von Unklarheiten oder Konflikten zwischen den \u00dcbersetzungen ist die englische Version ma\u00dfgebend und ma\u00dfgeblich. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Datenschutzbestimmungen Wer wir sind Mit Wirkung vom 26. Januar 2021 haben Assemble A\/S (&#8222;Assemble&#8220;) und seine Tochtergesellschaften (zusammen die &#8222;Assemble-Gruppe&#8220; oder &#8222;wir&#8220; oder &#8222;uns&#8220; oder &#8222;unser&#8220;) unsere Datenschutzrichtlinie aktualisiert. Zweck dieser Datenschutzrichtlinie Der Schutz Ihrer Daten ist wichtig. Wir verpflichten uns zur Sicherheit, zum Schutz und zur Vertraulichkeit von Informationen, die Sie uns oder in Ihrem Namen zur Verf\u00fcgung stellen oder bei denen es sich um Daten handelt, mit denen wir Sie durch die Bereitstellung von Datenverarbeitungs- und\/oder Datenspeicherdiensten unterst\u00fctzen. Diese Datenschutzrichtlinie beschreibt unsere aktuellen Richtlinien und Praktiken in Bezug auf alle pers\u00f6nlichen Daten, die wir von Ihnen direkt, \u00fcber die Website oder, falls Sie ein Elternteil, ein Vormund oder ein Betreuer sind, von einer Kindertagesst\u00e4tte oder Schule, mit der wir zusammenarbeiten, erhalten. Pers\u00f6nliche Daten sind alle Informationen, die Sie identifizieren, wie z. B. Ihr Name, Ihre E-Mail-Adresse, Ihre Telefonnummer und Ihre Position. Wie wir den Datenschutz einhalten In Anbetracht unserer Verantwortung, die Allgemeine Datenschutzverordnung und andere geltende Gesetze einzuhalten, haben wir entsprechendes Personal ernannt, das die Einhaltung aller Datenschutz- und E-Privacy-Vorschriften in unserem Unternehmen \u00fcberwacht und sicherstellt. Sie k\u00f6nnen sich an privacy@assemble.world wenden, wenn Sie Fragen haben oder weitere Informationen ben\u00f6tigen. Benachrichtigung \u00fcber \u00c4nderungen an unserer Datenschutzrichtlinie Wir verbessern st\u00e4ndig unsere Kommunikationsmethoden und f\u00fcgen dieser Website und unseren bestehenden Diensten neue Funktionen und Merkmale hinzu. Aufgrund dieser laufenden Ver\u00e4nderungen, Gesetzes\u00e4nderungen und der sich wandelnden Technologie werden sich unsere Datenschutzpraktiken von Zeit zu Zeit \u00e4ndern. Falls und wenn sich unsere Datenschutzpraktiken \u00e4ndern, werden wir diese Datenschutzerkl\u00e4rung aktualisieren, um unsere neuen Praktiken zu beschreiben. Wir empfehlen Ihnen, diese Seite regelm\u00e4\u00dfig zu besuchen. Diese Richtlinie wurde zuletzt am 26. Januar 2021 aktualisiert. Wir haben diese Richtlinie aktualisiert, um der Verantwortung Rechnung zu tragen, die wir im Rahmen der Allgemeinen Datenschutzverordnung haben werden. Die Informationen, die wir sammeln Wir speichern nur personenbezogene Daten, die f\u00fcr unsere Beziehungen zu einer bestimmten betroffenen Person unmittelbar relevant sind und deren Verarbeitung durch uns rechtm\u00e4\u00dfig erfolgen kann &#8211; zum Beispiel in Verfolgung unserer berechtigten Interessen, wie in dieser Richtlinie erl\u00e4utert, oder f\u00fcr Zwecke im Zusammenhang mit dem Abschluss eines Vertrags mit einer Organisation und der anschlie\u00dfenden Erf\u00fcllung dieses Vertrags. Diese Daten werden in der Art und Weise gespeichert und verarbeitet, wie wir sie in dieser Richtlinie beschreiben. M\u00f6glicherweise wurden Sie \u00fcber einen Link, den wir Ihnen zur Verf\u00fcgung gestellt haben, zu dieser Richtlinie weitergeleitet. Wir machen Einzelpersonen auf unsere Politik in Bezug auf den Besitz und die Verarbeitung der Daten dieser Person zum Zeitpunkt der Erhebung der betreffenden personenbezogenen Daten aufmerksam. Wie wir pers\u00f6nliche Informationen sammeln Wir k\u00f6nnen Ihre pers\u00f6nlichen Daten in dem Moment erfassen, in dem Sie eine Anfrage an Assemble A\/S stellen. Dazu geh\u00f6ren Ihre telefonischen Anfragen sowie Anfragen, die wir auf Messen und bei anderen Marketingaktivit\u00e4ten erhalten, die wir durchf\u00fchren. Wir nehmen Ihre Daten nur dann auf einer Grundlage auf, die uns berechtigt, diese pers\u00f6nlichen Daten zu speichern und zu verwenden, wenn Sie ausdr\u00fccklich zugestimmt haben, dass wir die Daten speichern d\u00fcrfen und f\u00fcr jeden Zweck, f\u00fcr den wir diese Daten verwenden wollen. Wir sammeln und speichern personenbezogene Daten \u00fcber Nutzer unserer Produkte und Dienstleistungen, wenn eine Anfrage oder Bitte um Unterst\u00fctzung an uns gerichtet wurde. Wenn Sie sich f\u00fcr eine Schulungsveranstaltung oder Konferenz anmelden, ben\u00f6tigen wir ebenfalls pers\u00f6nliche Daten, damit wir mit Ihnen \u00fcber die Veranstaltung kommunizieren k\u00f6nnen. Wenn Sie sich als Teilnehmer in einem von uns angebotenen Forum registrieren, werden wir Ihre Daten zum Zweck der Verwaltung des Forums speichern. Alle weiteren Daten, die Sie uns zur Verf\u00fcgung stellen, wie z.B. Lehrmaterial, Meinungen und Kommentare, werden aufbewahrt und stehen anderen registrierten Nutzern in \u00dcbereinstimmung mit den f\u00fcr das jeweilige Forum geltenden und dort angezeigten Regeln zur Verf\u00fcgung. Wir sammeln und verwenden Informationen von Nutzern, die unsere Dienste entweder \u00fcber mobile Anwendungen auf iOS (Apple App Store) oder Android (Google Play Store) oder \u00fcber unsere Webanwendungen nutzen. Unser Umgang mit Ihren pers\u00f6nlichen Informationen F\u00fcr unsere Marketingzwecke Wenn Sie jetzt oder zu einem sp\u00e4teren Zeitpunkt angeben, dass Sie damit einverstanden sind, werden wir die pers\u00f6nlichen Daten, die Sie uns zur Verf\u00fcgung stellen, aufbewahren, damit wir sie verwenden k\u00f6nnen: Sie zu kontaktieren, um Sie \u00fcber neue Dienstleistungen und Produkte zu informieren, die wir anbieten werden; Ihnen angeforderte Informationen \u00fcber unsere Dienstleistungen oder Produkte zu senden; oder Sie \u00fcber Aktualisierungen bei der Weiterentwicklung von Produkten und\/oder Dienstleistungen, f\u00fcr die Sie Interesse bekundet haben, zu informieren. Wir sind der Ansicht, dass wir Ihre pers\u00f6nlichen Daten im Rahmen der Verfolgung unserer legitimen Interessen als Unternehmen, das sich f\u00fcr den Erfolg des Bildungssektors einsetzt, verwenden d\u00fcrfen. Unsere E-Mails, die auf der oben genannten Grundlage bereitgestellt werden, enthalten immer eine Opt-out-Option f\u00fcr weitere Mitteilungen. F\u00fcr den Abschluss von Vertr\u00e4gen und die Verwaltung und Administration des Vertrags Wir verwenden die in unserem Besitz befindlichen pers\u00f6nlichen Daten, um Anfragen zu notieren, die in irgendeiner Weise gestellt werden, die im Rahmen des Vertrags vorgesehen ist. Dazu geh\u00f6rt auch die Nutzung der von uns angebotenen Helpline durch Nutzer unserer Produkte oder Dienstleistungen. Zum Zweck der Erbringung von Dienstleistungen, wie sie in unseren Vertr\u00e4gen mit Kindertagesst\u00e4tten und Schulen und anderen Kunden gefordert werden. Wir speichern Informationen \u00fcber bestimmte Personen f\u00fcr Zwecke im Zusammenhang mit der Verwaltung von Vertr\u00e4gen, die wir mit Kindertagesst\u00e4tten, Schulen und anderen Kunden unseres Unternehmens haben. Wir bewahren diese Informationen so lange auf, wie wir einen Vertrag mit der betreffenden Organisation haben oder bis wir \u00fcber einen Wechsel der Person(en) informiert werden, mit der\/denen wir im Rahmen der Verwaltung und des Managements des Vertrags arbeiten sollen. In diesem Fall werden die Daten der vorherigen Person sofort gel\u00f6scht, es sei denn, wir erhalten von dieser Person die Zustimmung, weiterhin in Bezug auf unsere Produkte und Dienstleistungen zu kommunizieren. Wir f\u00fchren Aufzeichnungen \u00fcber Personen, die sich an die von uns angebotenen Beratungsdienste wenden (dies gilt auch f\u00fcr F\u00e4lle, in denen eine Person uns auf anderem Wege kontaktiert, aber an den Helpdesk verwiesen wird). Wir verf\u00fcgen \u00fcber Angaben zu Ihrem Datenschutzbeauftragten oder, falls Sie keinen haben, zu der Person, die Sie als Verantwortlicher f\u00fcr Datenschutzangelegenheiten benannt haben. Von Zeit zu Zeit haben wir auch<\/p>\n","protected":false},"author":15,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","footnotes":""},"class_list":["post-238821","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Datenschutz und Politik | Nemb\u00f8rn<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nemborn.com\/de\/privacy-policy-4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz und Politik\" \/>\n<meta property=\"og:description\" content=\"Datenschutzbestimmungen Wer wir sind Mit Wirkung vom 26. Januar 2021 haben Assemble A\/S (&#8222;Assemble&#8220;) und seine Tochtergesellschaften (zusammen die &#8222;Assemble-Gruppe&#8220; oder &#8222;wir&#8220; oder &#8222;uns&#8220; oder &#8222;unser&#8220;) unsere Datenschutzrichtlinie aktualisiert. Zweck dieser Datenschutzrichtlinie Der Schutz Ihrer Daten ist wichtig. Wir verpflichten uns zur Sicherheit, zum Schutz und zur Vertraulichkeit von Informationen, die Sie uns oder in Ihrem Namen zur Verf\u00fcgung stellen oder bei denen es sich um Daten handelt, mit denen wir Sie durch die Bereitstellung von Datenverarbeitungs- und\/oder Datenspeicherdiensten unterst\u00fctzen. Diese Datenschutzrichtlinie beschreibt unsere aktuellen Richtlinien und Praktiken in Bezug auf alle pers\u00f6nlichen Daten, die wir von Ihnen direkt, \u00fcber die Website oder, falls Sie ein Elternteil, ein Vormund oder ein Betreuer sind, von einer Kindertagesst\u00e4tte oder Schule, mit der wir zusammenarbeiten, erhalten. Pers\u00f6nliche Daten sind alle Informationen, die Sie identifizieren, wie z. B. Ihr Name, Ihre E-Mail-Adresse, Ihre Telefonnummer und Ihre Position. Wie wir den Datenschutz einhalten In Anbetracht unserer Verantwortung, die Allgemeine Datenschutzverordnung und andere geltende Gesetze einzuhalten, haben wir entsprechendes Personal ernannt, das die Einhaltung aller Datenschutz- und E-Privacy-Vorschriften in unserem Unternehmen \u00fcberwacht und sicherstellt. Sie k\u00f6nnen sich an privacy@assemble.world wenden, wenn Sie Fragen haben oder weitere Informationen ben\u00f6tigen. Benachrichtigung \u00fcber \u00c4nderungen an unserer Datenschutzrichtlinie Wir verbessern st\u00e4ndig unsere Kommunikationsmethoden und f\u00fcgen dieser Website und unseren bestehenden Diensten neue Funktionen und Merkmale hinzu. Aufgrund dieser laufenden Ver\u00e4nderungen, Gesetzes\u00e4nderungen und der sich wandelnden Technologie werden sich unsere Datenschutzpraktiken von Zeit zu Zeit \u00e4ndern. Falls und wenn sich unsere Datenschutzpraktiken \u00e4ndern, werden wir diese Datenschutzerkl\u00e4rung aktualisieren, um unsere neuen Praktiken zu beschreiben. Wir empfehlen Ihnen, diese Seite regelm\u00e4\u00dfig zu besuchen. Diese Richtlinie wurde zuletzt am 26. Januar 2021 aktualisiert. Wir haben diese Richtlinie aktualisiert, um der Verantwortung Rechnung zu tragen, die wir im Rahmen der Allgemeinen Datenschutzverordnung haben werden. Die Informationen, die wir sammeln Wir speichern nur personenbezogene Daten, die f\u00fcr unsere Beziehungen zu einer bestimmten betroffenen Person unmittelbar relevant sind und deren Verarbeitung durch uns rechtm\u00e4\u00dfig erfolgen kann &#8211; zum Beispiel in Verfolgung unserer berechtigten Interessen, wie in dieser Richtlinie erl\u00e4utert, oder f\u00fcr Zwecke im Zusammenhang mit dem Abschluss eines Vertrags mit einer Organisation und der anschlie\u00dfenden Erf\u00fcllung dieses Vertrags. Diese Daten werden in der Art und Weise gespeichert und verarbeitet, wie wir sie in dieser Richtlinie beschreiben. M\u00f6glicherweise wurden Sie \u00fcber einen Link, den wir Ihnen zur Verf\u00fcgung gestellt haben, zu dieser Richtlinie weitergeleitet. Wir machen Einzelpersonen auf unsere Politik in Bezug auf den Besitz und die Verarbeitung der Daten dieser Person zum Zeitpunkt der Erhebung der betreffenden personenbezogenen Daten aufmerksam. Wie wir pers\u00f6nliche Informationen sammeln Wir k\u00f6nnen Ihre pers\u00f6nlichen Daten in dem Moment erfassen, in dem Sie eine Anfrage an Assemble A\/S stellen. Dazu geh\u00f6ren Ihre telefonischen Anfragen sowie Anfragen, die wir auf Messen und bei anderen Marketingaktivit\u00e4ten erhalten, die wir durchf\u00fchren. Wir nehmen Ihre Daten nur dann auf einer Grundlage auf, die uns berechtigt, diese pers\u00f6nlichen Daten zu speichern und zu verwenden, wenn Sie ausdr\u00fccklich zugestimmt haben, dass wir die Daten speichern d\u00fcrfen und f\u00fcr jeden Zweck, f\u00fcr den wir diese Daten verwenden wollen. Wir sammeln und speichern personenbezogene Daten \u00fcber Nutzer unserer Produkte und Dienstleistungen, wenn eine Anfrage oder Bitte um Unterst\u00fctzung an uns gerichtet wurde. Wenn Sie sich f\u00fcr eine Schulungsveranstaltung oder Konferenz anmelden, ben\u00f6tigen wir ebenfalls pers\u00f6nliche Daten, damit wir mit Ihnen \u00fcber die Veranstaltung kommunizieren k\u00f6nnen. Wenn Sie sich als Teilnehmer in einem von uns angebotenen Forum registrieren, werden wir Ihre Daten zum Zweck der Verwaltung des Forums speichern. Alle weiteren Daten, die Sie uns zur Verf\u00fcgung stellen, wie z.B. Lehrmaterial, Meinungen und Kommentare, werden aufbewahrt und stehen anderen registrierten Nutzern in \u00dcbereinstimmung mit den f\u00fcr das jeweilige Forum geltenden und dort angezeigten Regeln zur Verf\u00fcgung. Wir sammeln und verwenden Informationen von Nutzern, die unsere Dienste entweder \u00fcber mobile Anwendungen auf iOS (Apple App Store) oder Android (Google Play Store) oder \u00fcber unsere Webanwendungen nutzen. Unser Umgang mit Ihren pers\u00f6nlichen Informationen F\u00fcr unsere Marketingzwecke Wenn Sie jetzt oder zu einem sp\u00e4teren Zeitpunkt angeben, dass Sie damit einverstanden sind, werden wir die pers\u00f6nlichen Daten, die Sie uns zur Verf\u00fcgung stellen, aufbewahren, damit wir sie verwenden k\u00f6nnen: Sie zu kontaktieren, um Sie \u00fcber neue Dienstleistungen und Produkte zu informieren, die wir anbieten werden; Ihnen angeforderte Informationen \u00fcber unsere Dienstleistungen oder Produkte zu senden; oder Sie \u00fcber Aktualisierungen bei der Weiterentwicklung von Produkten und\/oder Dienstleistungen, f\u00fcr die Sie Interesse bekundet haben, zu informieren. Wir sind der Ansicht, dass wir Ihre pers\u00f6nlichen Daten im Rahmen der Verfolgung unserer legitimen Interessen als Unternehmen, das sich f\u00fcr den Erfolg des Bildungssektors einsetzt, verwenden d\u00fcrfen. Unsere E-Mails, die auf der oben genannten Grundlage bereitgestellt werden, enthalten immer eine Opt-out-Option f\u00fcr weitere Mitteilungen. F\u00fcr den Abschluss von Vertr\u00e4gen und die Verwaltung und Administration des Vertrags Wir verwenden die in unserem Besitz befindlichen pers\u00f6nlichen Daten, um Anfragen zu notieren, die in irgendeiner Weise gestellt werden, die im Rahmen des Vertrags vorgesehen ist. Dazu geh\u00f6rt auch die Nutzung der von uns angebotenen Helpline durch Nutzer unserer Produkte oder Dienstleistungen. Zum Zweck der Erbringung von Dienstleistungen, wie sie in unseren Vertr\u00e4gen mit Kindertagesst\u00e4tten und Schulen und anderen Kunden gefordert werden. Wir speichern Informationen \u00fcber bestimmte Personen f\u00fcr Zwecke im Zusammenhang mit der Verwaltung von Vertr\u00e4gen, die wir mit Kindertagesst\u00e4tten, Schulen und anderen Kunden unseres Unternehmens haben. Wir bewahren diese Informationen so lange auf, wie wir einen Vertrag mit der betreffenden Organisation haben oder bis wir \u00fcber einen Wechsel der Person(en) informiert werden, mit der\/denen wir im Rahmen der Verwaltung und des Managements des Vertrags arbeiten sollen. In diesem Fall werden die Daten der vorherigen Person sofort gel\u00f6scht, es sei denn, wir erhalten von dieser Person die Zustimmung, weiterhin in Bezug auf unsere Produkte und Dienstleistungen zu kommunizieren. Wir f\u00fchren Aufzeichnungen \u00fcber Personen, die sich an die von uns angebotenen Beratungsdienste wenden (dies gilt auch f\u00fcr F\u00e4lle, in denen eine Person uns auf anderem Wege kontaktiert, aber an den Helpdesk verwiesen wird). Wir verf\u00fcgen \u00fcber Angaben zu Ihrem Datenschutzbeauftragten oder, falls Sie keinen haben, zu der Person, die Sie als Verantwortlicher f\u00fcr Datenschutzangelegenheiten benannt haben. Von Zeit zu Zeit haben wir auch\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nemborn.com\/de\/privacy-policy-4\/\" \/>\n<meta property=\"og:site_name\" content=\"The Leading Childcare Management System &amp; Childcare App\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-25T11:20:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nemborn.com\/wp-content\/uploads\/2026\/05\/Childcare-Management-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"15\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nemborn.com\\\/de\\\/privacy-policy-4\\\/\",\"url\":\"https:\\\/\\\/nemborn.com\\\/de\\\/privacy-policy-4\\\/\",\"name\":\"Datenschutz und Politik | Nemb\u00f8rn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nemborn.com\\\/de\\\/#website\"},\"datePublished\":\"2025-09-25T11:10:57+00:00\",\"dateModified\":\"2025-09-25T11:20:12+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nemborn.com\\\/de\\\/privacy-policy-4\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nemborn.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/nemborn.com\\\/de\\\/\",\"name\":\"The Leading Childcare Management System & Childcare App\",\"description\":\"Die bevorzugte White-Label Kita Software und Kita App\",\"publisher\":{\"@id\":\"https:\\\/\\\/nemborn.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nemborn.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nemborn.com\\\/de\\\/#organization\",\"name\":\"The Leading Childcare Management System & Childcare App\",\"url\":\"https:\\\/\\\/nemborn.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/nemborn.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nemborn.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/nemborn-logo.png\",\"contentUrl\":\"https:\\\/\\\/nemborn.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/nemborn-logo.png\",\"width\":4142,\"height\":859,\"caption\":\"The Leading Childcare Management System & Childcare App\"},\"image\":{\"@id\":\"https:\\\/\\\/nemborn.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Datenschutz und Politik | Nemb\u00f8rn","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nemborn.com\/de\/privacy-policy-4\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutz und Politik","og_description":"Datenschutzbestimmungen Wer wir sind Mit Wirkung vom 26. Januar 2021 haben Assemble A\/S (&#8222;Assemble&#8220;) und seine Tochtergesellschaften (zusammen die &#8222;Assemble-Gruppe&#8220; oder &#8222;wir&#8220; oder &#8222;uns&#8220; oder &#8222;unser&#8220;) unsere Datenschutzrichtlinie aktualisiert. Zweck dieser Datenschutzrichtlinie Der Schutz Ihrer Daten ist wichtig. Wir verpflichten uns zur Sicherheit, zum Schutz und zur Vertraulichkeit von Informationen, die Sie uns oder in Ihrem Namen zur Verf\u00fcgung stellen oder bei denen es sich um Daten handelt, mit denen wir Sie durch die Bereitstellung von Datenverarbeitungs- und\/oder Datenspeicherdiensten unterst\u00fctzen. Diese Datenschutzrichtlinie beschreibt unsere aktuellen Richtlinien und Praktiken in Bezug auf alle pers\u00f6nlichen Daten, die wir von Ihnen direkt, \u00fcber die Website oder, falls Sie ein Elternteil, ein Vormund oder ein Betreuer sind, von einer Kindertagesst\u00e4tte oder Schule, mit der wir zusammenarbeiten, erhalten. Pers\u00f6nliche Daten sind alle Informationen, die Sie identifizieren, wie z. B. Ihr Name, Ihre E-Mail-Adresse, Ihre Telefonnummer und Ihre Position. Wie wir den Datenschutz einhalten In Anbetracht unserer Verantwortung, die Allgemeine Datenschutzverordnung und andere geltende Gesetze einzuhalten, haben wir entsprechendes Personal ernannt, das die Einhaltung aller Datenschutz- und E-Privacy-Vorschriften in unserem Unternehmen \u00fcberwacht und sicherstellt. Sie k\u00f6nnen sich an privacy@assemble.world wenden, wenn Sie Fragen haben oder weitere Informationen ben\u00f6tigen. Benachrichtigung \u00fcber \u00c4nderungen an unserer Datenschutzrichtlinie Wir verbessern st\u00e4ndig unsere Kommunikationsmethoden und f\u00fcgen dieser Website und unseren bestehenden Diensten neue Funktionen und Merkmale hinzu. Aufgrund dieser laufenden Ver\u00e4nderungen, Gesetzes\u00e4nderungen und der sich wandelnden Technologie werden sich unsere Datenschutzpraktiken von Zeit zu Zeit \u00e4ndern. Falls und wenn sich unsere Datenschutzpraktiken \u00e4ndern, werden wir diese Datenschutzerkl\u00e4rung aktualisieren, um unsere neuen Praktiken zu beschreiben. Wir empfehlen Ihnen, diese Seite regelm\u00e4\u00dfig zu besuchen. Diese Richtlinie wurde zuletzt am 26. Januar 2021 aktualisiert. Wir haben diese Richtlinie aktualisiert, um der Verantwortung Rechnung zu tragen, die wir im Rahmen der Allgemeinen Datenschutzverordnung haben werden. Die Informationen, die wir sammeln Wir speichern nur personenbezogene Daten, die f\u00fcr unsere Beziehungen zu einer bestimmten betroffenen Person unmittelbar relevant sind und deren Verarbeitung durch uns rechtm\u00e4\u00dfig erfolgen kann &#8211; zum Beispiel in Verfolgung unserer berechtigten Interessen, wie in dieser Richtlinie erl\u00e4utert, oder f\u00fcr Zwecke im Zusammenhang mit dem Abschluss eines Vertrags mit einer Organisation und der anschlie\u00dfenden Erf\u00fcllung dieses Vertrags. Diese Daten werden in der Art und Weise gespeichert und verarbeitet, wie wir sie in dieser Richtlinie beschreiben. M\u00f6glicherweise wurden Sie \u00fcber einen Link, den wir Ihnen zur Verf\u00fcgung gestellt haben, zu dieser Richtlinie weitergeleitet. Wir machen Einzelpersonen auf unsere Politik in Bezug auf den Besitz und die Verarbeitung der Daten dieser Person zum Zeitpunkt der Erhebung der betreffenden personenbezogenen Daten aufmerksam. Wie wir pers\u00f6nliche Informationen sammeln Wir k\u00f6nnen Ihre pers\u00f6nlichen Daten in dem Moment erfassen, in dem Sie eine Anfrage an Assemble A\/S stellen. Dazu geh\u00f6ren Ihre telefonischen Anfragen sowie Anfragen, die wir auf Messen und bei anderen Marketingaktivit\u00e4ten erhalten, die wir durchf\u00fchren. Wir nehmen Ihre Daten nur dann auf einer Grundlage auf, die uns berechtigt, diese pers\u00f6nlichen Daten zu speichern und zu verwenden, wenn Sie ausdr\u00fccklich zugestimmt haben, dass wir die Daten speichern d\u00fcrfen und f\u00fcr jeden Zweck, f\u00fcr den wir diese Daten verwenden wollen. Wir sammeln und speichern personenbezogene Daten \u00fcber Nutzer unserer Produkte und Dienstleistungen, wenn eine Anfrage oder Bitte um Unterst\u00fctzung an uns gerichtet wurde. Wenn Sie sich f\u00fcr eine Schulungsveranstaltung oder Konferenz anmelden, ben\u00f6tigen wir ebenfalls pers\u00f6nliche Daten, damit wir mit Ihnen \u00fcber die Veranstaltung kommunizieren k\u00f6nnen. Wenn Sie sich als Teilnehmer in einem von uns angebotenen Forum registrieren, werden wir Ihre Daten zum Zweck der Verwaltung des Forums speichern. Alle weiteren Daten, die Sie uns zur Verf\u00fcgung stellen, wie z.B. Lehrmaterial, Meinungen und Kommentare, werden aufbewahrt und stehen anderen registrierten Nutzern in \u00dcbereinstimmung mit den f\u00fcr das jeweilige Forum geltenden und dort angezeigten Regeln zur Verf\u00fcgung. Wir sammeln und verwenden Informationen von Nutzern, die unsere Dienste entweder \u00fcber mobile Anwendungen auf iOS (Apple App Store) oder Android (Google Play Store) oder \u00fcber unsere Webanwendungen nutzen. Unser Umgang mit Ihren pers\u00f6nlichen Informationen F\u00fcr unsere Marketingzwecke Wenn Sie jetzt oder zu einem sp\u00e4teren Zeitpunkt angeben, dass Sie damit einverstanden sind, werden wir die pers\u00f6nlichen Daten, die Sie uns zur Verf\u00fcgung stellen, aufbewahren, damit wir sie verwenden k\u00f6nnen: Sie zu kontaktieren, um Sie \u00fcber neue Dienstleistungen und Produkte zu informieren, die wir anbieten werden; Ihnen angeforderte Informationen \u00fcber unsere Dienstleistungen oder Produkte zu senden; oder Sie \u00fcber Aktualisierungen bei der Weiterentwicklung von Produkten und\/oder Dienstleistungen, f\u00fcr die Sie Interesse bekundet haben, zu informieren. Wir sind der Ansicht, dass wir Ihre pers\u00f6nlichen Daten im Rahmen der Verfolgung unserer legitimen Interessen als Unternehmen, das sich f\u00fcr den Erfolg des Bildungssektors einsetzt, verwenden d\u00fcrfen. Unsere E-Mails, die auf der oben genannten Grundlage bereitgestellt werden, enthalten immer eine Opt-out-Option f\u00fcr weitere Mitteilungen. F\u00fcr den Abschluss von Vertr\u00e4gen und die Verwaltung und Administration des Vertrags Wir verwenden die in unserem Besitz befindlichen pers\u00f6nlichen Daten, um Anfragen zu notieren, die in irgendeiner Weise gestellt werden, die im Rahmen des Vertrags vorgesehen ist. Dazu geh\u00f6rt auch die Nutzung der von uns angebotenen Helpline durch Nutzer unserer Produkte oder Dienstleistungen. Zum Zweck der Erbringung von Dienstleistungen, wie sie in unseren Vertr\u00e4gen mit Kindertagesst\u00e4tten und Schulen und anderen Kunden gefordert werden. Wir speichern Informationen \u00fcber bestimmte Personen f\u00fcr Zwecke im Zusammenhang mit der Verwaltung von Vertr\u00e4gen, die wir mit Kindertagesst\u00e4tten, Schulen und anderen Kunden unseres Unternehmens haben. Wir bewahren diese Informationen so lange auf, wie wir einen Vertrag mit der betreffenden Organisation haben oder bis wir \u00fcber einen Wechsel der Person(en) informiert werden, mit der\/denen wir im Rahmen der Verwaltung und des Managements des Vertrags arbeiten sollen. In diesem Fall werden die Daten der vorherigen Person sofort gel\u00f6scht, es sei denn, wir erhalten von dieser Person die Zustimmung, weiterhin in Bezug auf unsere Produkte und Dienstleistungen zu kommunizieren. Wir f\u00fchren Aufzeichnungen \u00fcber Personen, die sich an die von uns angebotenen Beratungsdienste wenden (dies gilt auch f\u00fcr F\u00e4lle, in denen eine Person uns auf anderem Wege kontaktiert, aber an den Helpdesk verwiesen wird). Wir verf\u00fcgen \u00fcber Angaben zu Ihrem Datenschutzbeauftragten oder, falls Sie keinen haben, zu der Person, die Sie als Verantwortlicher f\u00fcr Datenschutzangelegenheiten benannt haben. Von Zeit zu Zeit haben wir auch","og_url":"https:\/\/nemborn.com\/de\/privacy-policy-4\/","og_site_name":"The Leading Childcare Management System &amp; Childcare App","article_modified_time":"2025-09-25T11:20:12+00:00","og_image":[{"width":2560,"height":1066,"url":"https:\/\/nemborn.com\/wp-content\/uploads\/2026\/05\/Childcare-Management-scaled.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"15\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nemborn.com\/de\/privacy-policy-4\/","url":"https:\/\/nemborn.com\/de\/privacy-policy-4\/","name":"Datenschutz und Politik | Nemb\u00f8rn","isPartOf":{"@id":"https:\/\/nemborn.com\/de\/#website"},"datePublished":"2025-09-25T11:10:57+00:00","dateModified":"2025-09-25T11:20:12+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nemborn.com\/de\/privacy-policy-4\/"]}]},{"@type":"WebSite","@id":"https:\/\/nemborn.com\/de\/#website","url":"https:\/\/nemborn.com\/de\/","name":"The Leading Childcare Management System & Childcare App","description":"Die bevorzugte White-Label Kita Software und Kita App","publisher":{"@id":"https:\/\/nemborn.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nemborn.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/nemborn.com\/de\/#organization","name":"The Leading Childcare Management System & Childcare App","url":"https:\/\/nemborn.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nemborn.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/nemborn.com\/wp-content\/uploads\/2020\/04\/nemborn-logo.png","contentUrl":"https:\/\/nemborn.com\/wp-content\/uploads\/2020\/04\/nemborn-logo.png","width":4142,"height":859,"caption":"The Leading Childcare Management System & Childcare App"},"image":{"@id":"https:\/\/nemborn.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nemborn.com\/de\/wp-json\/wp\/v2\/pages\/238821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nemborn.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nemborn.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nemborn.com\/de\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/nemborn.com\/de\/wp-json\/wp\/v2\/comments?post=238821"}],"version-history":[{"count":0,"href":"https:\/\/nemborn.com\/de\/wp-json\/wp\/v2\/pages\/238821\/revisions"}],"wp:attachment":[{"href":"https:\/\/nemborn.com\/de\/wp-json\/wp\/v2\/media?parent=238821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}